{"id":53952,"date":"2016-06-07T04:00:12","date_gmt":"2016-06-07T10:00:12","guid":{"rendered":"https:\/\/whatsupusana.com\/2016\/06\/usana-innove-eu\/"},"modified":"2016-06-07T04:00:12","modified_gmt":"2016-06-07T10:00:12","slug":"usana-innove-eu","status":"publish","type":"post","link":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/","title":{"rendered":"Certaines entreprises suivent le courant. USANA innove."},"content":{"rendered":"<p>Prendre les devants. Ne jamais embo\u00eeter le pas. Ne jamais se contenter de ce qui existe. Faire preuve d\u2019audace \u2013 surtout s\u2019il s\u2019agit de briser le statu quo.<\/p>\n<p><a href=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/10\/laboratory.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-46880 size-medium\" src=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/10\/laboratory-395x400.jpg\" alt=\"laboratory\" width=\"395\" height=\"400\" srcset=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/10\/laboratory-395x400.jpg 395w, https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/10\/laboratory.jpg 650w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/a>Ce n&rsquo;est pas n\u00e9cessairement ce qu&rsquo;on recherche dans un profil sur un site de rencontres, ni dans une note envoy\u00e9e par l\u2019institutrice de son enfant. Par contre, c&rsquo;est exactement ce qu&rsquo;on esp\u00e8re trouver dans la pr\u00e9sentation d\u2019une entreprise de produits nutritionnels.<\/p>\n<p>Et nous sommes fiers de faire n\u00f4tres tous ces traits dominants. Avec nous, rien n\u2019est jamais d\u00e9finitif et nous ne saurions nous contenter de suivre le courant. Nous avons sans cesse sur notre table de travail la prochaine grande innovation susceptible d&rsquo;avoir un impact sur votre sant\u00e9.<\/p>\n<h4><strong>Un sens inn\u00e9 de l\u2019innovation<\/strong><\/h4>\n<p>Il y a une excellente raison pour cette fa\u00e7on d&rsquo;\u00eatre. La fondation de notre entreprise trouve son origine dans un grand concept qui a marqu\u00e9 un point de rupture avec la science de la nutrition. Notre attitude \u2013 qualifions-la de refus du statu quo ou d&rsquo;esprit d\u2019innovation \u2013 n&rsquo;a pas chang\u00e9 en plus de deux d\u00e9cennies.<\/p>\n<p>C\u2019est pourquoi l\u2019histoire d\u2019USANA suit une ligne continue qui relie une innovation \u00e0 la suivante.<\/p>\n<p><a href=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/03\/10-Secrets-to-Lasting-Change-Carmen-Marshall-2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-45100 size-medium\" src=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/03\/10-Secrets-to-Lasting-Change-Carmen-Marshall-2-280x400.jpg\" alt=\"10 Secrets to Lasting Change - Carmen Marshall 2\" width=\"280\" height=\"400\" srcset=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/03\/10-Secrets-to-Lasting-Change-Carmen-Marshall-2-280x400.jpg 280w, https:\/\/whatsupusana.com\/wp-content\/uploads\/2014\/03\/10-Secrets-to-Lasting-Change-Carmen-Marshall-2.jpg 500w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/a>Tout a commenc\u00e9 en 1992 avec les Essentials<sup>\u2122<\/sup> d\u2019USANA<sup>\u00ae <\/sup>\u2013 des antioxydants en doses optimales \u2013 pour se poursuivre avec Olivol<sup>\u00ae<\/sup>. Viennent ensuite les produits de soins de la peau aux propri\u00e9t\u00e9s d\u2019auto-pr\u00e9servation, MyHealthPak<sup>\u2122<\/sup> et la technologie nutritionnelle hybride, l\u2019\u00c9valuation de la sant\u00e9 v\u00e9ritable, puis enfin, les produits MySmart<sup>\u2122<\/sup>Foods d\u2019USANA. Et il manque presque autant d\u2019innovations que nous en avons \u00e9num\u00e9r\u00e9es ici.<\/p>\n<h4><strong>Un h\u00e9ritage qui se perp\u00e9tue<\/strong><\/h4>\n<p>Le temps est venu d&rsquo;ajouter un nouveau chapitre \u00e0 notre histoire car nous sommes loin d&rsquo;avoir fini d&rsquo;innover.<\/p>\n<p>Nous sommes tout simplement incapables d&rsquo;agir autrement. En ce moment m\u00eame, dans un immeuble de la r\u00e9gion ouest de Salt Lake City, une autre innovation importante de pr\u00e9pare. Et c&rsquo;est une innovation de taille.<\/p>\n<p>Savons-nous en quoi elle consiste? Bien s\u00fbr que oui. Nous sommes-nous engag\u00e9s \u00e0 la garder secr\u00e8te? On pourrait dire \u00e7a. Chose certaine par contre, nous pouvons vous r\u00e9v\u00e9ler la date de son d\u00e9voilement : le 25 ao\u00fbt 2016, au congr\u00e8s international d\u2019USANA.<\/p>\n<p>Le compte \u00e0 rebours commence d\u00e8s maintenant.<\/p>\n<div class=\"hdivider\"><\/div>\n<p><strong><span style=\"font-size: x-small;\"><em>We\u2019re proud to bring you the freshest content on the web! Follow <a title=\"USANA Twitter\" href=\"http:\/\/twitter.com\/USANAinc\" target=\"_blank\">USANA<\/a> on Twitter, like our <a title=\"USANA Facebook\" href=\"http:\/\/www.facebook.com\/USANAHealthSciences\" target=\"_blank\">USANA<\/a> Facebook page and enjoy the latest videos on the official <a title=\"USANA YouTube\" href=\"http:\/\/www.youtube.com\/user\/USANAHealthSciences\" target=\"_blank\">USANA<\/a> YouTube channel.<\/em><\/span><\/strong><\/p>\n<p><strong><span style=\"font-size: x-small;\"><a href=\"http:\/\/www.usanafoundation.org\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"USANA True Health Foundation\" src=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2012\/05\/USANA-Foundation.jpg\" alt=\"USANA True Health Foundation\" width=\"50\" height=\"50\" \/><\/a><em>Learn what <a title=\"USANA True Health Foundation\" href=\"http:\/\/www.usanafoundation.org\/\" target=\"_blank\">USANA<\/a> is doing to make the world a better place.<\/em><\/span><\/strong><\/p>\n<p><strong><span style=\"font-size: x-small;\"><em>The future of personalized health and nutrition is now available with USANA\u2019s <a title=\"USANA True Health Assessment\" href=\"http:\/\/www.truehealthassessment.com\/demo\" target=\"_blank\">True Health Assessment<\/a>.<\/em><\/span><\/strong><\/p>\n<div class=\"hdivider\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prendre les devants. Ne jamais embo\u00eeter le pas. Ne jamais se contenter de ce qui existe. Faire preuve d\u2019audace \u2013 surtout s\u2019il s\u2019agit de briser le statu quo. Ce n&rsquo;est pas n\u00e9cessairement ce qu&rsquo;on recherche dans un profil sur un site de rencontres, ni dans une note envoy\u00e9e par l\u2019institutrice de son enfant. Par contre, [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":53951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2353],"tags":[2416,2421],"class_list":["post-53952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-french-fr","tag-usana-french-fr"],"better_featured_image":{"id":53951,"alt_text":"","caption":"","description":"Innovation","media_type":"image","media_details":{"width":1600,"height":900,"file":"2016\/06\/Innovation_featured.jpg","sizes":{"thumbnail":{"file":"Innovation_featured-225x127.jpg","width":225,"height":127,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-225x127.jpg"},"medium":{"file":"Innovation_featured-400x225.jpg","width":400,"height":225,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-400x225.jpg"},"medium_large":{"file":"Innovation_featured-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-768x432.jpg"},"large":{"file":"Innovation_featured-725x408.jpg","width":725,"height":408,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-725x408.jpg"},"narrow-featured-image":{"file":"Innovation_featured-680x300.jpg","width":680,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-680x300.jpg"},"wide-featured-image":{"file":"Innovation_featured-800x450.jpg","width":800,"height":450,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-800x450.jpg"},"wide-thumbnail":{"file":"Innovation_featured-675x240.jpg","width":675,"height":240,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-675x240.jpg"},"small-wide-thumbnail":{"file":"Innovation_featured-352x198.jpg","width":352,"height":198,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-352x198.jpg"},"thumbnav":{"file":"Innovation_featured-140x90.jpg","width":140,"height":90,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-140x90.jpg"},"featured-page":{"file":"Innovation_featured-400x160.jpg","width":400,"height":160,"mime-type":"image\/jpeg","source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured-400x160.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":53950,"source_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certaines entreprises suivent le courant. USANA innove.<\/title>\n<meta name=\"description\" content=\"Certaines entreprises suivent le courant. USANA innove.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certaines entreprises suivent le courant. USANA innove.\" \/>\n<meta property=\"og:description\" content=\"Certaines entreprises suivent le courant. USANA innove.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/\" \/>\n<meta property=\"og:site_name\" content=\"What&#039;s Up, USANA?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/usanahealthsciences%e2%80%8e\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-07T10:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Baker\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Baker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/\"},\"author\":{\"name\":\"David Baker\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/#\\\/schema\\\/person\\\/e0e6ae7fa7602ea7f36ac3f36766cb21\"},\"headline\":\"Certaines entreprises suivent le courant. USANA innove.\",\"datePublished\":\"2016-06-07T10:00:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/\"},\"wordCount\":474,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatsupusana.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Innovation_featured.jpg\",\"keywords\":[\"French\",\"USANA French\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/\",\"url\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/\",\"name\":\"Certaines entreprises suivent le courant. USANA innove.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatsupusana.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Innovation_featured.jpg\",\"datePublished\":\"2016-06-07T10:00:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/#\\\/schema\\\/person\\\/e0e6ae7fa7602ea7f36ac3f36766cb21\"},\"description\":\"Certaines entreprises suivent le courant. USANA innove.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whatsupusana.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Innovation_featured.jpg\",\"contentUrl\":\"https:\\\/\\\/whatsupusana.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Innovation_featured.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/2016\\\/06\\\/usana-innove-eu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certaines entreprises suivent le courant. USANA innove.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/\",\"name\":\"What&#039;s Up, USANA?\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/#\\\/schema\\\/person\\\/e0e6ae7fa7602ea7f36ac3f36766cb21\",\"name\":\"David Baker\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g\",\"caption\":\"David Baker\"},\"url\":\"https:\\\/\\\/whatsupusana.com\\\/fr\\\/author\\\/davidb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certaines entreprises suivent le courant. USANA innove.","description":"Certaines entreprises suivent le courant. USANA innove.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/","og_locale":"fr_FR","og_type":"article","og_title":"Certaines entreprises suivent le courant. USANA innove.","og_description":"Certaines entreprises suivent le courant. USANA innove.","og_url":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/","og_site_name":"What&#039;s Up, USANA?","article_publisher":"https:\/\/www.facebook.com\/usanahealthsciences%e2%80%8e","article_published_time":"2016-06-07T10:00:12+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","type":"image\/jpeg"}],"author":"David Baker","twitter_misc":{"\u00c9crit par":"David Baker","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#article","isPartOf":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/"},"author":{"name":"David Baker","@id":"https:\/\/whatsupusana.com\/fr\/#\/schema\/person\/e0e6ae7fa7602ea7f36ac3f36766cb21"},"headline":"Certaines entreprises suivent le courant. USANA innove.","datePublished":"2016-06-07T10:00:12+00:00","mainEntityOfPage":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/"},"wordCount":474,"commentCount":0,"image":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#primaryimage"},"thumbnailUrl":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","keywords":["French","USANA French"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/","url":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/","name":"Certaines entreprises suivent le courant. USANA innove.","isPartOf":{"@id":"https:\/\/whatsupusana.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#primaryimage"},"image":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#primaryimage"},"thumbnailUrl":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","datePublished":"2016-06-07T10:00:12+00:00","author":{"@id":"https:\/\/whatsupusana.com\/fr\/#\/schema\/person\/e0e6ae7fa7602ea7f36ac3f36766cb21"},"description":"Certaines entreprises suivent le courant. USANA innove.","breadcrumb":{"@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#primaryimage","url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","contentUrl":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/whatsupusana.com\/fr\/2016\/06\/usana-innove-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whatsupusana.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Certaines entreprises suivent le courant. USANA innove."}]},{"@type":"WebSite","@id":"https:\/\/whatsupusana.com\/fr\/#website","url":"https:\/\/whatsupusana.com\/fr\/","name":"What&#039;s Up, USANA?","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whatsupusana.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/whatsupusana.com\/fr\/#\/schema\/person\/e0e6ae7fa7602ea7f36ac3f36766cb21","name":"David Baker","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ccdbe5eed023916a40ec60e0f815d54e6fa5088da49b4e31dadca6c2acf207b?s=96&d=blank&r=g","caption":"David Baker"},"url":"https:\/\/whatsupusana.com\/fr\/author\/davidb\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/whatsupusana.com\/wp-content\/uploads\/2016\/06\/Innovation_featured.jpg","_links":{"self":[{"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/posts\/53952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/comments?post=53952"}],"version-history":[{"count":0,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/posts\/53952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/media\/53951"}],"wp:attachment":[{"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/media?parent=53952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/categories?post=53952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whatsupusana.com\/fr\/wp-json\/wp\/v2\/tags?post=53952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}